{"id":22,"count":5,"description":"","link":"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News Archives - Pointe Dental Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News Archives - Pointe Dental Group\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Pointe Dental Group\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/category\\\/news\\\/\",\"url\":\"https:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/category\\\/news\\\/\",\"name\":\"News Archives - Pointe Dental Group\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/category\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/category\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/\",\"name\":\"Pointe Dental Group\",\"description\":\"Grosse Pointe &amp; Shelby Twp\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.pointedentalgroup.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News Archives - Pointe Dental Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/","og_locale":"en_US","og_type":"article","og_title":"News Archives - Pointe Dental Group","og_url":"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/","og_site_name":"Pointe Dental Group","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/","url":"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/","name":"News Archives - Pointe Dental Group","isPartOf":{"@id":"http:\/\/www.pointedentalgroup.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pointedentalgroup.com\/blog\/category\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.pointedentalgroup.com\/blog\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"http:\/\/www.pointedentalgroup.com\/blog\/#website","url":"http:\/\/www.pointedentalgroup.com\/blog\/","name":"Pointe Dental Group","description":"Grosse Pointe &amp; Shelby Twp","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.pointedentalgroup.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.pointedentalgroup.com\/blog\/wp-json\/wp\/v2\/categories\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pointedentalgroup.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.pointedentalgroup.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.pointedentalgroup.com\/blog\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}